{"id":5184,"date":"2022-05-23T20:41:14","date_gmt":"2022-05-23T23:41:14","guid":{"rendered":"https:\/\/www.padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/05\/img_9294-large.jpeg"},"modified":"2022-05-23T20:41:14","modified_gmt":"2022-05-23T23:41:14","slug":"img_9294-large","status":"inherit","type":"attachment","link":"https:\/\/padrelascasas.cl\/newplc\/200-estudiantes-de-padre-las-casas-participaron-de-la-7a-version-del-campeonato-de-futbol-escolar-copa-aniversario-de-carabineros\/img_9294-large\/","title":{"rendered":"img_9294-large"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"pgc_sgb_lightbox_settings":""},"class_list":["post-5184","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/05\/img_9294-large.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/05\/img_9294-large-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/05\/img_9294-large-300x200.jpeg 300w, https:\/\/padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/05\/img_9294-large-1024x683.jpeg 1024w, https:\/\/padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/05\/img_9294-large-768x512.jpeg 768w, https:\/\/padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/05\/img_9294-large-1536x1024.jpeg 1536w, https:\/\/padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/05\/img_9294-large.jpeg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1600,"height":1067,"file":"2022\/05\/img_9294-large.jpeg","sizes":{"medium":{"file":"img_9294-large-300x200.jpeg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/05\/img_9294-large-300x200.jpeg"},"large":{"file":"img_9294-large-1024x683.jpeg","width":1024,"height":683,"mime_type":"image\/jpeg","source_url":"https:\/\/padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/05\/img_9294-large-1024x683.jpeg"},"thumbnail":{"file":"img_9294-large-150x150.jpeg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/05\/img_9294-large-150x150.jpeg"},"medium_large":{"file":"img_9294-large-768x512.jpeg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/05\/img_9294-large-768x512.jpeg"},"1536x1536":{"file":"img_9294-large-1536x1024.jpeg","width":1536,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/05\/img_9294-large-1536x1024.jpeg"},"full":{"file":"img_9294-large.jpeg","width":1600,"height":1067,"mime_type":"image\/jpeg","source_url":"https:\/\/padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/05\/img_9294-large.jpeg"}},"image_meta":{"aperture":"10","credit":"","camera":"Canon EOS REBEL T5i","caption":"","created_timestamp":"1652971349","copyright":"([None] (Photographer) - [None]","focal_length":"18","iso":"100","shutter_speed":"0.004","title":"","orientation":"1","keywords":[]}},"post":5130,"source_url":"https:\/\/padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/05\/img_9294-large.jpeg","_links":{"self":[{"href":"https:\/\/padrelascasas.cl\/newplc\/wp-json\/wp\/v2\/media\/5184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/padrelascasas.cl\/newplc\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/padrelascasas.cl\/newplc\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/padrelascasas.cl\/newplc\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/padrelascasas.cl\/newplc\/wp-json\/wp\/v2\/comments?post=5184"}]}}