{"id":6978,"date":"2022-11-25T15:14:37","date_gmt":"2022-11-25T18:14:37","guid":{"rendered":"https:\/\/www.padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/11\/Equipos-de-Salud-del-Centro-Comunitario-de-Rehabilitacion-de-Padre-Las-Casas-entregan-ayudas-tecnicas-a-familias-de-la-comuna-2-Mediano.jpg"},"modified":"2022-11-25T15:14:37","modified_gmt":"2022-11-25T18:14:37","slug":"equipos-de-salud-del-centro-comunitario-de-rehabilitacion-de-padre-las-casas-entregan-ayudas-tecnicas-a-familias-de-la-comuna-2-mediano","status":"inherit","type":"attachment","link":"https:\/\/padrelascasas.cl\/newplc\/equipos-de-salud-del-centro-comunitario-de-rehabilitacion-de-padre-las-casas-entregan-ayudas-tecnicas-a-familias-de-la-comuna\/equipos-de-salud-del-centro-comunitario-de-rehabilitacion-de-padre-las-casas-entregan-ayudas-tecnicas-a-familias-de-la-comuna-2-mediano\/","title":{"rendered":"Equipos de Salud del Centro Comunitario de Rehabilitaci\u00f3n de Padre Las Casas entregan ayudas t\u00e9cnicas a familias de la comuna (2) (Mediano)"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"pgc_sgb_lightbox_settings":""},"class_list":["post-6978","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/11\/Equipos-de-Salud-del-Centro-Comunitario-de-Rehabilitacion-de-Padre-Las-Casas-entregan-ayudas-tecnicas-a-familias-de-la-comuna-2-Mediano.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/11\/Equipos-de-Salud-del-Centro-Comunitario-de-Rehabilitacion-de-Padre-Las-Casas-entregan-ayudas-tecnicas-a-familias-de-la-comuna-2-Mediano-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/11\/Equipos-de-Salud-del-Centro-Comunitario-de-Rehabilitacion-de-Padre-Las-Casas-entregan-ayudas-tecnicas-a-familias-de-la-comuna-2-Mediano-300x200.jpg 300w, https:\/\/padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/11\/Equipos-de-Salud-del-Centro-Comunitario-de-Rehabilitacion-de-Padre-Las-Casas-entregan-ayudas-tecnicas-a-familias-de-la-comuna-2-Mediano-1024x683.jpg 1024w, https:\/\/padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/11\/Equipos-de-Salud-del-Centro-Comunitario-de-Rehabilitacion-de-Padre-Las-Casas-entregan-ayudas-tecnicas-a-familias-de-la-comuna-2-Mediano-768x512.jpg 768w, https:\/\/padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/11\/Equipos-de-Salud-del-Centro-Comunitario-de-Rehabilitacion-de-Padre-Las-Casas-entregan-ayudas-tecnicas-a-familias-de-la-comuna-2-Mediano.jpg 1152w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1152,"height":768,"file":"2022\/11\/Equipos-de-Salud-del-Centro-Comunitario-de-Rehabilitacion-de-Padre-Las-Casas-entregan-ayudas-tecnicas-a-familias-de-la-comuna-2-Mediano.jpg","filesize":217193,"sizes":{"medium":{"file":"Equipos-de-Salud-del-Centro-Comunitario-de-Rehabilitacion-de-Padre-Las-Casas-entregan-ayudas-tecnicas-a-familias-de-la-comuna-2-Mediano-300x200.jpg","width":300,"height":200,"filesize":42735,"mime_type":"image\/jpeg","source_url":"https:\/\/padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/11\/Equipos-de-Salud-del-Centro-Comunitario-de-Rehabilitacion-de-Padre-Las-Casas-entregan-ayudas-tecnicas-a-familias-de-la-comuna-2-Mediano-300x200.jpg"},"large":{"file":"Equipos-de-Salud-del-Centro-Comunitario-de-Rehabilitacion-de-Padre-Las-Casas-entregan-ayudas-tecnicas-a-familias-de-la-comuna-2-Mediano-1024x683.jpg","width":1024,"height":683,"filesize":131266,"mime_type":"image\/jpeg","source_url":"https:\/\/padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/11\/Equipos-de-Salud-del-Centro-Comunitario-de-Rehabilitacion-de-Padre-Las-Casas-entregan-ayudas-tecnicas-a-familias-de-la-comuna-2-Mediano-1024x683.jpg"},"thumbnail":{"file":"Equipos-de-Salud-del-Centro-Comunitario-de-Rehabilitacion-de-Padre-Las-Casas-entregan-ayudas-tecnicas-a-familias-de-la-comuna-2-Mediano-150x150.jpg","width":150,"height":150,"filesize":35353,"mime_type":"image\/jpeg","source_url":"https:\/\/padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/11\/Equipos-de-Salud-del-Centro-Comunitario-de-Rehabilitacion-de-Padre-Las-Casas-entregan-ayudas-tecnicas-a-familias-de-la-comuna-2-Mediano-150x150.jpg"},"medium_large":{"file":"Equipos-de-Salud-del-Centro-Comunitario-de-Rehabilitacion-de-Padre-Las-Casas-entregan-ayudas-tecnicas-a-familias-de-la-comuna-2-Mediano-768x512.jpg","width":768,"height":512,"filesize":93097,"mime_type":"image\/jpeg","source_url":"https:\/\/padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/11\/Equipos-de-Salud-del-Centro-Comunitario-de-Rehabilitacion-de-Padre-Las-Casas-entregan-ayudas-tecnicas-a-familias-de-la-comuna-2-Mediano-768x512.jpg"},"full":{"file":"Equipos-de-Salud-del-Centro-Comunitario-de-Rehabilitacion-de-Padre-Las-Casas-entregan-ayudas-tecnicas-a-familias-de-la-comuna-2-Mediano.jpg","width":1152,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/11\/Equipos-de-Salud-del-Centro-Comunitario-de-Rehabilitacion-de-Padre-Las-Casas-entregan-ayudas-tecnicas-a-familias-de-la-comuna-2-Mediano.jpg"}},"image_meta":{"aperture":"4","credit":"e","camera":"Canon EOS Rebel T6","caption":"","created_timestamp":"1669196375","copyright":"","focal_length":"18","iso":"800","shutter_speed":"0.016666666666667","title":"","orientation":"1","keywords":[]}},"post":6977,"source_url":"https:\/\/padrelascasas.cl\/newplc\/wp-content\/uploads\/2022\/11\/Equipos-de-Salud-del-Centro-Comunitario-de-Rehabilitacion-de-Padre-Las-Casas-entregan-ayudas-tecnicas-a-familias-de-la-comuna-2-Mediano.jpg","_links":{"self":[{"href":"https:\/\/padrelascasas.cl\/newplc\/wp-json\/wp\/v2\/media\/6978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/padrelascasas.cl\/newplc\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/padrelascasas.cl\/newplc\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/padrelascasas.cl\/newplc\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/padrelascasas.cl\/newplc\/wp-json\/wp\/v2\/comments?post=6978"}]}}